{"id":7286,"date":"2026-02-03T08:13:05","date_gmt":"2026-02-03T07:13:05","guid":{"rendered":"https:\/\/www.hsu-hh.de\/wiso\/?post_type=tribe_events&#038;p=7286"},"modified":"2026-02-03T08:13:05","modified_gmt":"2026-02-03T07:13:05","slug":"gastvortrag-dr-lucy-chebout-verfassungsrichterin-berlin-aufgedraengte-natuerlichkeit-zur-bedeutung-von-leiblicher-abstammung-und-geschlecht-im-recht-der-eltern-kind-zuordnung","status":"publish","type":"tribe_events","link":"https:\/\/www.hsu-hh.de\/wiso\/event\/gastvortrag-dr-lucy-chebout-verfassungsrichterin-berlin-aufgedraengte-natuerlichkeit-zur-bedeutung-von-leiblicher-abstammung-und-geschlecht-im-recht-der-eltern-kind-zuordnung","title":{"rendered":"Gastvortrag Dr. Lucy Chebout (Verfassungsrichterin Berlin) &#8222;Aufgedr\u00e4ngte Nat\u00fcrlichkeit Zur Bedeutung von leiblicher Abstammung und Geschlecht im Recht der Eltern-Kind-Zuordnung&#8220;"},"content":{"rendered":"<p>Der Vortrag wird hochschul\u00f6ffentlich gehalten. Ich bitte die Kollegen\/Kolleginnen, Ihre Mitarbeiter\/Mitarbeiterinnen und Studierende auf die Vortr\u00e4ge aufmerksam zu machen.<\/p>\n<p>Initiatorin: <abbr title=\"Professor\">Prof.<\/abbr> <abbr title=\"Doktor\">Dr.<\/abbr> Dana-Sophia Valentiner<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Vortrag wird hochschul\u00f6ffentlich gehalten. Ich bitte die Kollegen\/Kolleginnen, Ihre Mitarbeiter\/Mitarbeiterinnen und Studierende auf die Vortr\u00e4ge aufmerksam zu machen. Initiatorin: Prof. Dr. Dana-Sophia Valentiner<\/p>\n","protected":false},"author":37,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-7286","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events\/7286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/users\/37"}],"version-history":[{"count":1,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events\/7286\/revisions"}],"predecessor-version":[{"id":7288,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events\/7286\/revisions\/7288"}],"wp:attachment":[{"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/media?parent=7286"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tags?post=7286"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events_cat?post=7286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}