{"id":6602,"date":"2024-10-22T06:52:22","date_gmt":"2024-10-22T04:52:22","guid":{"rendered":"https:\/\/www.hsu-hh.de\/wiso\/?post_type=tribe_events&#038;p=6602"},"modified":"2024-10-22T06:52:23","modified_gmt":"2024-10-22T04:52:23","slug":"gastvortrag-prof-dr-martin-beck-centrum-fuer-nah-und-mittelost-studien-cnms-marburg-endlose-besatzung-strukturelle-hindernisse-einer-kooperativen-bearbeitung-des-israelisch-palaestinensisch","status":"publish","type":"tribe_events","link":"https:\/\/www.hsu-hh.de\/wiso\/event\/gastvortrag-prof-dr-martin-beck-centrum-fuer-nah-und-mittelost-studien-cnms-marburg-endlose-besatzung-strukturelle-hindernisse-einer-kooperativen-bearbeitung-des-israelisch-palaestinensisch","title":{"rendered":"Gastvortrag Prof. Dr. Martin Beck (Centrum f\u00fcr Nah- und Mittelost-Studien (CNMS), Marburg) &#8222;Endlose Besatzung? Strukturelle Hindernisse einer kooperativen Bearbeitung des israelisch-pal\u00e4stinensischen Konflikts&#8220;"},"content":{"rendered":"<p>Der Vortrag wird hochschul\u00f6ffentlich gehalten. Wir bitten die Kollegen\/Kolleginnen, Ihre Mitarbeiter\/Mitarbeiterinnen und Studierende auf die Vortr\u00e4ge aufmerksam zu machen.<\/p>\n<p>Initiatorin: <abbr title=\"Professor\">Prof.<\/abbr> <abbr title=\"Doktor\">Dr.<\/abbr> J\u00fcnemann<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Vortrag wird hochschul\u00f6ffentlich gehalten. Wir bitten die Kollegen\/Kolleginnen, Ihre Mitarbeiter\/Mitarbeiterinnen und Studierende auf die Vortr\u00e4ge aufmerksam zu machen. Initiatorin: Prof. Dr. J\u00fcnemann<\/p>\n","protected":false},"author":37,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-6602","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events\/6602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/users\/37"}],"version-history":[{"count":1,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events\/6602\/revisions"}],"predecessor-version":[{"id":6603,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events\/6602\/revisions\/6603"}],"wp:attachment":[{"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/media?parent=6602"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tags?post=6602"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.hsu-hh.de\/wiso\/wp-json\/wp\/v2\/tribe_events_cat?post=6602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}