{"id":1985,"date":"2020-02-28T14:13:15","date_gmt":"2020-02-28T13:13:15","guid":{"rendered":"https:\/\/www.hsu-hh.de\/sportzentrum\/?post_type=tribe_events&#038;p=1985"},"modified":"2020-05-12T11:58:12","modified_gmt":"2020-05-12T09:58:12","slug":"teilnahme-einer-deutschen-delegation-an-den-world-cadet-games-2020-in-sankt-petersburg-rus","status":"publish","type":"tribe_events","link":"https:\/\/www.hsu-hh.de\/sportzentrum\/event\/teilnahme-einer-deutschen-delegation-an-den-world-cadet-games-2020-in-sankt-petersburg-rus","title":{"rendered":"VERSCHOBEN! Teilnahme einer Deutschen Delegation an den World Cadet Games 2020 in Sankt Petersburg \/ RUS"},"content":{"rendered":"<p>Die Deutsche Delegation nimmt im Zeitraum 15.08. bis 23.08.2019 mit einer Abordnung der beiden Universit\u00e4ten der Bundeswehr an den 3. CISM World Cadet Games in Sankt Petersburg (Russland) teil, um gleichsam die sportliche Leistungsf\u00e4higkeit der deutschen Offizieranw\u00e4rter\/innen w\u00fcrdig gegen\u00fcber den Streitkr\u00e4ften anderer Nationen unter Beweis zu stellen und engagierten und verdienten Kameradinnen und Kameraden die M\u00f6glichkeit zum internationalen Austausch mit dem Offiziernachwuchs anderer Nationen zu erm\u00f6glichen.<\/p>\n<p>Ziele sind hierbei:<\/p>\n<ul>\n<li>F\u00f6rderung der Motivation zum nachhaltigen Training und zur zielgerichteten sportlichen Vorbereitung<\/li>\n<li>Bestenauslese durch objektive Kriterien<\/li>\n<li>Leistungsvergleich unter den studierenden Offizieranw\u00e4rterinnen und Offizieranw\u00e4rtern<\/li>\n<li>Heranf\u00fchrung des Offiziernachwuchses an das Thema internationaler Milit\u00e4rsport \/ CISM<\/li>\n<li>Schaffung eines realen alltagsnahen Projektes f\u00fcr Studierende der Sportwissenschaften an der UniBw M\u00fcnchen<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Die Deutsche Delegation nimmt im Zeitraum 15.08. bis 23.08.2019 mit einer Abordnung der beiden Universit\u00e4ten der Bundeswehr an den 3. CISM World Cadet Games in Sankt Petersburg (Russland) teil, um [&hellip;]<\/p>\n","protected":false},"author":1742,"featured_media":0,"template":"","meta":{"_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-1985","tribe_events","type-tribe_events","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/tribe_events\/1985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/users\/1742"}],"version-history":[{"count":2,"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/tribe_events\/1985\/revisions"}],"predecessor-version":[{"id":2006,"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/tribe_events\/1985\/revisions\/2006"}],"wp:attachment":[{"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/media?parent=1985"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/tags?post=1985"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.hsu-hh.de\/sportzentrum\/wp-json\/wp\/v2\/tribe_events_cat?post=1985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}